{"id":64,"date":"2013-05-16T12:59:37","date_gmt":"2013-05-16T10:59:37","guid":{"rendered":"http:\/\/www.joerglipinski.de\/blog\/?p=64"},"modified":"2026-06-24T10:58:14","modified_gmt":"2026-06-24T08:58:14","slug":"aufruf-europa-geht-anders","status":"publish","type":"post","link":"http:\/\/www.joerglipinski.de\/blog\/aufruf-europa-geht-anders\/","title":{"rendered":"Aufruf: Europa geht anders"},"content":{"rendered":"<p>Dieser Aufruf d\u00fcrfte diejenigen interessieren, die die Eurozone noch nicht ganz abgeschrieben haben. Da die dort publizierten Inhalte zu einem Gro\u00dfteil auch meiner Ansicht zum Stand der Dinge in der Eurokrise entsprechen, habe ich den Aufruf bereits unterzeichnet&#8230;<\/p>\n<p><center><a href=\"http:\/\/www.europa-geht-anders.eu\/\" title=\"Europa geht anders\" target=\"_blank\"><IMG SRC=\"https:\/\/ausgetrock.net\/sites\/default\/files\/styles\/680px\/public\/images\/europa-geht-anders_logo-edited-by_ausgetrocknet.png\" width=\"600\"\/><\/a><\/center><\/p>\n<p>Zitat aus dem Aufruf:<br \/>\n<strong>Aufruf: Europa geht anders!<br \/>\nDemokratie und Soziale Sicherheit in Europa statt weiterer Sozialabbau durch \u201eWettbewerbspakt\u201c!<\/strong><br \/>\nEuropa kommt nicht aus der Krise. Die Menschen in Europa befinden sich in der Mitte eines verlorenen Jahrzehnts. Mit jedem Jahr seit Krisenbeginn verschlechtern sich die Nachrichten. Die Arbeitslosigkeit in der Europ\u00e4ischen Union erreicht Rekordniveaus: 26 Millionen Menschen haben keinen Arbeitsplatz, rund 10 Millionen mehr als vor der Finanzkrise. Monat f\u00fcr Monat steigt die Zahl der Erwerbslosen um fast 200.000. <\/p>\n<p>In Spanien und Griechenland betr\u00e4gt die Arbeitslosenquote unter Jugendlichen bereits fast 60 Prozent. In den meisten L\u00e4ndern sinken seit Jahren die Reall\u00f6hne. In Zahlen l\u00e4sst sich das damit verbundene menschliche Elend nicht fassen: In Athen sind hunderttausende Menschen auf Suppenk\u00fcchen angewiesen, in Spanien kommt es trotz leerstehender Wohnungen zu massenhaften Zwangsr\u00e4umungen. Heizen k\u00f6nnen sich viele Menschen im Winter nicht mehr leisten. Das sind Verh\u00e4ltnisse, die in Europa als l\u00e4ngst \u00fcberwunden galten!<\/p>\n<p>Die Krise, die Europa erfasst hat, kam nicht \u00fcberraschend. Sie ist das Ergebnis einer neoliberalen Politik, die auf den Wettbewerb der Staaten, Marktgl\u00e4ubigkeit und eine weitgehend unregulierte Finanzindustrie setzte. Das Vertrauen auf die \u00dcberlegenheit der M\u00e4rkte hat sich als kolossaler Irrtum erwiesen. Die kontinuierliche Umverteilung von unten nach oben hat in eine Sackgasse gef\u00fchrt. Angewachsen sind riesige Privatverm\u00f6gen einerseits und (Einkommens-)Armut, ungesicherte Arbeitsverh\u00e4ltnisse, Ausbeutung und wachsende Arbeitslosigkeit auf der anderen Seite.<br \/>\n&#8230;<\/p>\n<p>Ich m\u00f6chte diesen Aufruf hier ausdr\u00fccklich empfehlen und weise noch einmal darauf hin, dass ich ihn selbst auch unterst\u00fctze&#8230;<\/p>","protected":false},"excerpt":{"rendered":"<p>Dieser Aufruf d\u00fcrfte diejenigen interessieren, die die Eurozone noch nicht ganz abgeschrieben haben. Da die dort publizierten Inhalte zu einem Gro\u00dfteil auch meiner Ansicht zum Stand der Dinge in der Eurokrise entsprechen, habe ich den Aufruf bereits unterzeichnet&#8230; Zitat aus<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[16,15,18],"class_list":["post-64","post","type-post","status-publish","format-standard","hentry","category-oekonomie","tag-lohnstueckkosten","tag-produktivitaet","tag-wirtschaft"],"_links":{"self":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":14,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"predecessor-version":[{"id":9421676,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/64\/revisions\/9421676"}],"wp:attachment":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}