{"id":5508712,"date":"2017-05-13T07:00:23","date_gmt":"2017-05-13T05:00:23","guid":{"rendered":"http:\/\/www.joerglipinski.de\/blog\/?p=5508712"},"modified":"2026-05-18T09:38:53","modified_gmt":"2026-05-18T07:38:53","slug":"blick-in-die-usa-die-oeffentlichkeit-ist-der-irrigen-ansicht-dass-sie-eine-geringe-inflation-besonders-moegen-wuerde","status":"publish","type":"post","link":"http:\/\/www.joerglipinski.de\/blog\/blick-in-die-usa-die-oeffentlichkeit-ist-der-irrigen-ansicht-dass-sie-eine-geringe-inflation-besonders-moegen-wuerde\/","title":{"rendered":"Blick in die USA: Die \u00d6ffentlichkeit ist der irrigen Ansicht, dass sie eine geringe Inflation besonders m\u00f6gen w\u00fcrde"},"content":{"rendered":"<p>Umfragen zeigen, dass die \u00d6ffentlichkeit offenbar der Ansicht ist, eine niedrige Inflation w\u00e4re besonders positiv. Aber das stimmt so einfach dann doch nicht. <\/p>\n<p><Center><a href=\"https:\/\/www.econlib.org\/wp-content\/uploads\/2017\/04\/Screen20Shot202017-04-1320at201.58.1420PM.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" border=\"0\" style=\"border:0;\" src=\"https:\/\/www.econlib.org\/wp-content\/uploads\/2017\/04\/Screen20Shot202017-04-1320at201.58.1420PM.png\" width=\"400\" \/><\/a><\/Center><\/p>\n<p>Der Glaube, eine niedrige Inflation sei gut ist eine logische Folge  der Fixierung auf Preisver\u00e4nderungen, was allerdings tats\u00e4chlich fast immer eher eine schlechte Idee darstellt. So sollten wir sehr skeptisch sein, wenn die \u00d6ffentlichkeit behauptet, eine geringe Inflation besonders zu lieben. <\/p>\n<p><!--more Weiterlesen...--><\/p>\n<p>Tats\u00e4chlich gilt das nur, wenn diese niedrige Inflation \u00fcber ein gleichzeitig ansteigendes Gesamtangebot generiert wird. Im Gegensatz dazu hasst die \u00f6ffentliche Meinung eine geringe Inflation geradezu, wenn sie durch eine sinkende aggregierte Nachfrage (wie beispielsweise mittels einer gestrafften Geldpolitik) hervorgerufen wird.<\/p>\n<p>Obiges Diagramm zeigt die Ergebnisse <a href=\"http:\/\/www.pewresearch.org\/fact-tank\/2015\/01\/20\/us-economy\/\" target=\"_blank\" rel=\"noopener\">verschiedener Meinungsumfragen<\/a> in Bezug auf die wirtschaftliche Entwicklung in den USA.<\/p>\n<p>Wie man erkennen kann, sank die positive Sicht der \u00d6ffentlichkeit auf die Wirtschaft im ersten Halbjahr 2008 stark, da mit der Finanzkrise ein nachteiliger Angebotsschock die Inflation ansteigen lie\u00df. Doch Anfang 2009 war die Inflation auf etwa Null gefallen, den niedrigsten Wert seit 1955. Und trotzdem st\u00fcrzte das Vertrauen der \u00d6ffentlichkeit in die Wirtschaft weiter ab auf ein extrem geringes Niveau.<\/p>\n<p>Manche w\u00fcrden nun einwenden, dass bei dieser Argumentation andere Faktoren unber\u00fccksichtigt bleiben &#8211; denn auch die Arbeitslosigkeit hatte sich im Fr\u00fchjahr 2009 stark erh\u00f6ht. Das ist zwar richtig, doch die Erwerbslosigkeit stieg ja gerade deshalb so heftig, <em>weil die strikte Geldpolitik die Inflation auf Null gesetzt hatte<\/em>. (Das w\u00e4re in etwa so, als w\u00fcrde man sagen, dass jemand nichts dagegen h\u00e4tte, aus dem 100. Stock eines Geb\u00e4uden zu st\u00fcrzen, aber nicht auf dem Boden aufschlagen wolle) Die \u00d6ffentlichkeit kann behaupten, eine niedrige Inflation zu m\u00f6gen, aber dann verhielte sie sich so, als ob sie eigentlich eine niedrige Arbeitslosigkeit meint. <\/p>\n<p>Die obige Grafik spiegelt das reale BIP-Wachstum und die Entwicklung der Arbeitslosenquote weitaus genauer wieder als die Inflationsrate. Das Wachstum sank und die Arbeitslosigkeit stieg in 2008 und Anfang 2009, als die Meinung der \u00d6ffentlichkeit zur wirtschaftlichen Entwicklung immer negativer wurde. <\/p>\n<p>Dann hat sie sich allm\u00e4hlich verbessert, als die Erwerbslosigkeit zur\u00fcckging und die Wirtschaft sich erholte. Im Gegensatz dazu ist die Inflation heute h\u00f6her als im Jahr 2009. W\u00e4hrend sie anstieg, hat sich demnach auch das Vertrauen der \u00d6ffentlichkeit in die wirtschaftliche Entwicklung verbessert.<\/p>\n<p>Meiner Ansicht nach gibt es keine &#8222;\u00f6ffentliche Meinung&#8220;, wenn es um Inflation geht. F\u00fcr die \u00d6ffentlichkeit bedeutet der Begriff &#8222;Inflation&#8220; etwas ganz anderes als das, was er f\u00fcr \u00d6konomen darstellt. Umfragen wiesen nach, dass 1990 die meisten Amerikaner der Ansicht waren, die Inflation sei h\u00f6her als 10 Jahre zuvor gewesen (tats\u00e4chlich aber war sie von 13% auf 4% gefallen). M\u00f6glicherweise haben sie dabei auch nur die &#8222;Inflation&#8220; mit den &#8222;Lebenshaltungskosten&#8220; verwechselt. In j\u00fcngster Zeit stieg die Inflation dann wieder auf 2%, und doch ist das Ansehen der Wirtschaft in der \u00d6ffentlichkeit jetzt positiver als in vielen Jahren zuvor.<\/p>\n<p>Wenn ein Zentralbanker eine \u00f6ffentliche Meinungsumfrage lesen sollte, die zeigt, dass die Menschen gegen eine h\u00f6here Inflation opponieren und daraufhin beschlie\u00dft, die Inflationsrate auf Null zu senken, w\u00fcrden sie eine unangenehme \u00dcberraschung erleben. Was auch immer Sie \u00fcber &#8222;\u00f6ffentliche Meinung&#8220; und Inflation meinen, denken Sie daran, dass die \u00d6ffentlichkeit eine \u00d6konomie mit null Inflation als Folge einer gestrafften Geldpolitik absolut nicht will. Wir haben das im Jahr 2009 gesehen und wir w\u00fcrden es wieder sehen, wenn die Fed pl\u00f6tzlich die Inflation auf Null herunterfahren w\u00fcrde.<\/p>\n<p>Ein <a href=\"http:\/\/www.themoneyillusion.com\/?p=32415#comment-1901662\" target=\"_blank\" rel=\"noopener\">Kommentator<\/a> schrieb dazu vor kurzem:<\/p>\n<blockquote><p>\nIch denke, dass die \u00d6ffentlichkeit auch empfindlich reagiert auf die Tatsache, dass das Auftreten steigender Inflation scheinbar vor allem die am meisten gef\u00e4hrdeten trifft. Eben die Erwerbslosen und\/oder diejenigen, die auf irgendeine Art von festen Einkommen angewiesen sind, welche nicht inflationsbereinigt sind.<\/p><\/blockquote>\n<p>Tats\u00e4chlich aber sind es gerade die Arbeitslosen, denen am meisten durch die Inflation geholfen werden kann, wenn sie durch monet\u00e4re Impulse induziert wird. (Dagegen schadet Inflation durch die Angebotsseite fast allen.) Nachfrage-Inflation tendiert in der Regel dazu, Arbeitspl\u00e4tze f\u00fcr Erwerbslose zu generieren. <\/p>\n<p>Soweit es allerdings die &#8222;verwundbaren&#8220; Menschen mit festen Einkommen betrifft, sind diese typischerweise aber gar nicht arm. Die Armen neigen viel eher dazu, sich auf Programme der Sozialen Absicherungen zu verlassen, die gegen die Inflation indexiert sind. Menschen mit nichtindexierten Annuit\u00e4ten geh\u00f6ren dagegen wahrscheinlich mindestens der Mittelschicht an.<\/p>\n<p><em>(eigene \u00dcbersetzung eines <a href=\"http:\/\/econlog.econlib.org\/archives\/2017\/04\/the_public_only.html\" target=\"_blank\" rel=\"noopener\">Blogbeitrages<\/a> des amerikanischen \u00d6konomen <a href=\"https:\/\/de.wikipedia.org\/wiki\/Scott_Sumner\" target=\"_blank\" rel=\"noopener\">Scott Sumner<\/a>)<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Umfragen zeigen, dass die \u00d6ffentlichkeit offenbar der Ansicht ist, eine niedrige Inflation w\u00e4re besonders positiv. Aber das stimmt so einfach dann doch nicht. Der Glaube, eine niedrige Inflation sei gut ist eine logische Folge der Fixierung auf Preisver\u00e4nderungen, was allerdings<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[33,34,44,18],"class_list":["post-5508712","post","type-post","status-publish","format-standard","hentry","category-oekonomie","tag-deflation","tag-inflation","tag-volkswirtschaftslehre","tag-wirtschaft"],"_links":{"self":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/5508712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/comments?post=5508712"}],"version-history":[{"count":22,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/5508712\/revisions"}],"predecessor-version":[{"id":8766787,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/5508712\/revisions\/8766787"}],"wp:attachment":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/media?parent=5508712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/categories?post=5508712"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/tags?post=5508712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}