{"id":24291205,"date":"2024-05-20T07:51:32","date_gmt":"2024-05-20T05:51:32","guid":{"rendered":"http:\/\/www.joerglipinski.de\/blog\/?p=24291205"},"modified":"2026-04-22T10:01:33","modified_gmt":"2026-04-22T08:01:33","slug":"noch-einmal-ueber-die-verlorene-freizeit-unseres-lebens","status":"publish","type":"post","link":"http:\/\/www.joerglipinski.de\/blog\/noch-einmal-ueber-die-verlorene-freizeit-unseres-lebens\/","title":{"rendered":"Noch einmal: \u00dcber die verlorene Freizeit unseres Lebens"},"content":{"rendered":"<p><a href=\"https:\/\/de.wikipedia.org\/wiki\/John_Maynard_Keynes\" target=\"_blank\" rel=\"noopener\">John Maynard Keynes<\/a> lag schon richtig mit seiner Vorhersage, dass wir weniger arbeiten werden, doch er \u00fcbersch\u00e4tzte, wie lange dieser Trend tats\u00e4chlich anhalten w\u00fcrde.<\/p>\n<p><Center><a title=\"Freizeit im Garten von lilie M\u00e9lo from france (week-end-pleasure) [CC BY 2.0 (http:\/\/creativecommons.org\/licenses\/by\/2.0)], via Wikimedia Commons\" href=\"https:\/\/commons.wikimedia.org\/wiki\/File%3AWeek-end_pleasure.jpg\"><img decoding=\"async\" width=\"412\" alt=\"Week-end pleasure\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/2\/25\/Week-end_pleasure.jpg\"\/><\/a><br \/>\n<em>Freizeit-Vergn\u00fcgen im Garten<\/em><\/center><\/p>\n<p>&#8222;Drei Stunden am Tag sind genug&#8220;, schrieb Keynes 1930 in seinem  Essay <a href=\"http:\/\/www.econ.yale.edu\/smith\/econ116a\/keynes1.pdf\" target=\"_blank\" rel=\"noopener\">&#8222;Economic Possibilities for our Grandchildren&#8220;<\/a> (dt.: Die wirtschaftlichen M\u00f6glichkeiten f\u00fcr unsere Enkelkinder). <\/p>\n<p><!--more Weiterlesen...--><\/p>\n<p>Dieser Aufsatz fesselt seine Leser auch heute noch, vor allem dank seiner fabelhaften, aber durchaus richtigen Prognose, dass es in den fortgeschrittenen Volkswirtschaften Menschen im Jahr 2030 bis zu acht Mal besser gehen sollte als im Jahr 1930 &#8211; gekoppelt mit einer Vorhersage, die dagegen spektakul\u00e4r falsch zu sein scheint, n\u00e4mlich dass wir nur noch 15-Stunden-Wochen arbeiten w\u00fcrden.<\/p>\n<p>Im Jahre 2008 gaben die beiden \u00d6konomen <a href=\"https:\/\/mitpress.mit.edu\/authors\/lorenzo-pecchi\" target=\"_blank\" rel=\"noopener\">Lorenzo Pecchi<\/a> und <a href=\"https:\/\/mitpress.mit.edu\/authors\/gustavo-piga\" target=\"_blank\" rel=\"noopener\">Gustavo Piga<\/a> ein <a href=\"https:\/\/mitpress.mit.edu\/books\/revisiting-keynes\" target=\"_blank\" rel=\"noopener\">Buch<\/a> heraus, in dem bekannte Wirtschaftswissenschaftler  \u00fcber Keynes&#8216; Essay diskutierten. Einer der Beteiligten, <a href=\"https:\/\/de.wikipedia.org\/wiki\/Benjamin_M._Friedman\" target=\"_blank\" rel=\"noopener\">Benjamin Friedman<\/a> von der <a href=\"https:\/\/de.wikipedia.org\/wiki\/Harvard_University\" target=\"_blank\" rel=\"noopener\">Harvard University<\/a>, griff sp\u00e4ter noch einmal <a href=\"http:\/\/papers.ssrn.com\/sol3\/papers.cfm?abstract_id=2691231\" target=\"_blank\" rel=\"noopener\">die Frage auf<\/a>, wo Keynes falsch gelegen habe und produzierte dabei eine zum Nachdenken anregende Antwort.<\/p>\n<p>Erstens, es lohne sich durchaus, die Art und das Ausma\u00df von Keynes&#8216; Fehler etwas n\u00e4her zu unter-suchen. Er hatte n\u00e4mlich recht bei seiner Vorhersage, dass wir weniger arbeiten w\u00fcrden. Wir treten heute sp\u00e4ter ins Arbeitsleben ein, nach langen und nicht-immer-m\u00fchsamen Studieng\u00e4ngen. Wir genie\u00dfen fr\u00fchere Pensionierungen. <\/p>\n<p>Die Arbeitswoche selbst wird immer k\u00fcrzer. In der nicht-landwirtschaftlichen Besch\u00e4ftigung in den USA dauerte die Woche im Jahr 1930 69 Stunden &#8211; das entspricht einer Arbeitszeit von 11 Stunden pro Tag, aber nur drei Stunden am Sonntag. Bis 1930 verringerte sich eine Vollzeitarbeitswoche auf 47 Stunden; mit jedem Jahrzehnt arbeiteten die amerikanischen Arbeiter 2 Stunden weniger pro Woche.<\/p>\n<p>Aber Keynes hatte schlicht \u00fcbersch\u00e4tzt, wie schnell und wie lange sich dieser Trend fortsetzen w\u00fcrde. Bis 1970 betrug die Arbeitszeit pro Woche nur noch 39 Stunden. Wenn die Arbeitswoche so weiter geschrumpft w\u00e4re, w\u00fcrden wir jetzt 30-Stunden-Wochen arbeiten, und vielleicht 25-Stunden-Wochen bis 2030. Doch um 1970 herum stoppte diese Verk\u00fcrzung. Aber warum?<\/p>\n<p>Eine naheliegende Antwort w\u00e4re, dass die Leute einfach nie zufrieden sind: vielleicht wird ihr Wunsch zu konsumieren von Werbung und Anzeigen entz\u00fcndet; vielleicht liegt es auch nur daran, dass man immer ein besseres Auto, einen tolleren Anzug oder eine geschmackvollere K\u00fcche als die Nachbarn besitzen will. Da aber auch diese Mitmenschen immer wohlhabender werden, gibt es an diesem Prozess nichts, was einem eine Auszeit davon g\u00f6nnen k\u00f6nnte.<\/p>\n<p>Kein Zweifel, an dieser Ansicht ist viel dran. Doch Friedman w\u00e4hlt noch einen anderen Blickwinkel. Anstatt zu fragen, warum Keynes die  Einkommen so richtig, aber die Freizeit so falsch eingesch\u00e4tzt hatte, weist er darauf hin, dass Keynes vielleicht das Einkommen anders betrachtete, als wir es in der Regel heute tun. Denn w\u00e4hrend die US-Wirtschaft bis zur Krise 2007 kr\u00e4ftig wuchs, begannen die mittleren Haushaltseinkommen bereits lange vorher zu stagnieren &#8211; tats\u00e4chlich ab etwa 1970.<\/p>\n<p>Die L\u00fccke zwischen dem Wachstum der Wirtschaft und der Zunahme des mittleren Haushalts-einkommen wird durch einen Flickenteppich von verschiedenen Faktoren erkl\u00e4rt, einschlie\u00dflich einer Ver\u00e4nderung in der Natur der Haushalte selbst, es muss mehr Einkommen abgezweigt werden, um die Kosten im Gesundheitswesen tragen zu k\u00f6nnen und ein zunehmender Anteil der realisierten Ertr\u00e4ge sammeln sich bei den Topverdienern an. <\/p>\n<p>Kurz gefasst sind die Fortschritte in Richtung der 15-Stunden-Woche vielleicht deshalb ins Stocken geraten, weil die typischen US-Haushalts-Einkommen ebenso ins Stocken geraten sind. Die Einkommen der Haushalte begannen zur gleichen Zeit zu stagnieren, als die Arbeitswoche aufh\u00f6rte zu schrumpfen.<\/p>\n<p>Diese Idee erscheint sinnvoll, aber sie erkl\u00e4rt noch nicht, was bei den h\u00f6heren Einkommensgruppen geschieht. Da ihre Einkommen nicht stagnieren &#8211; sie sind weit davon entfernt &#8211; k\u00f6nnte man erwarten, dass sie einige der Vorteile der sehr hohen Stundenl\u00f6hne in Form von k\u00fcrzeren Arbeitstagen und l\u00e4ngeren Wochenenden in Anspruch nehmen w\u00fcrden. <\/p>\n<p>Doch dem ist anscheinend nicht so. Nach <a href=\"http:\/\/qje.oxfordjournals.org\/content\/122\/3\/969.short\" target=\"_blank\" rel=\"noopener\">Recherchen<\/a> der beiden \u00d6konomen <a href=\"https:\/\/en.wikipedia.org\/wiki\/Mark_Aguiar\" target=\"_blank\" rel=\"noopener\">Mark Aguiar<\/a> und <a href=\"https:\/\/www.chicagobooth.edu\/faculty\/directory\/h\/erik-hurst\" target=\"_blank\" rel=\"noopener\">Erik Hurst<\/a> aus dem Jahr 2006 &#8211; eine sch\u00f6ne Momentaufnahme des Lebens vor der gro\u00dfen Rezession &#8211; genossen Bezieher h\u00f6herer Einkommen weniger Freizeit.<\/p>\n<p>So hat sich das Puzzle in eine andere Form gebracht. Gew\u00f6hnliche Menschen fr\u00f6nen ein gewisses Ma\u00df an Einkommensgewinnen und mehr Freizeit, so wie Keynes es vorhergesagt hatte &#8211; aber doch eher weniger von beidem, als wir seiner Prognose nach h\u00e4tten erwarten k\u00f6nnen.<\/p>\n<p>Die Wirtschaftseliten verk\u00f6rpern dagegen auch weiterhin eine Art Paradoxon: sie erhalten alle Einkom-mensgewinne, die Keynes vorhergesagt hatte und auch noch mehr, aber eben auf Kosten einer begrenzten Freizeit.<\/p>\n<p>Der wahrscheinliche Grund daf\u00fcr ist wohl, dass es in vielen Karrieren schwer ist, in die oberen R\u00e4nge durchzubrechen, ohne dabei lange Stunden zu investieren. Es ist offenbar nicht so einfach, es nur mit einer 20-Stunden-Woche in die C-Suite zu schaffen, egal wie talentiert man ist. <\/p>\n<p>Und weil die Einkommensverteilung stark verzerrt ist, sind die Eins\u00e4tze hoch: 70 Stunden pro Woche arbeiten als w\u00e4re es noch 1830 bedeutet eben die Vorrausetzung f\u00fcr einen sechsstelligen Bonus, w\u00e4hrend 35 Stunden pro Woche f\u00fcr die Karriere viel zu wenig sind.<\/p>\n<p>Die Folgen all dieser Verteilungskonflikte k\u00f6nnen dann auch an eher unerwarteten Orten auftauchen. Wie eine <a href=\"http:\/\/ftp.iza.org\/dp9502.pdf\" target=\"_blank\" rel=\"noopener\">Forschungsarbeit<\/a> der Wirtschaftswissenschaftlerinnen <a href=\"http:\/\/econ.columbia.edu\/lena-edlund\" target=\"_blank\" rel=\"noopener\">Lena Edlund<\/a>, <a href=\"https:\/\/sites.google.com\/site\/machadoc\/\" target=\"_blank\" rel=\"noopener\">Cecilia Machado<\/a> und <a href=\"http:\/\/www.micaelasviatschi.com\/\" target=\"_blank\" rel=\"noopener\">Maria Micaela Sviatschi<\/a> nachweist, waren die st\u00e4dtischen Zentren in den USA die unerw\u00fcnschten Lebensr\u00e4ume in den sp\u00e4ten 1970er und fr\u00fchen 1980er Jahren. Die Leute zahlten lieber eine Pr\u00e4mie, um in den Vororten leben zu k\u00f6nnen und pendelten in die Stadtzentren zur Arbeit. <\/p>\n<p>Heute hat sich diese Situation total ver\u00e4ndert. Warum? Die Antwort lautet nach Edlund und ihren Kolleginnen, dass wohlhabende Menschen keine Zeit mehr zum Pendeln haben. Sie zahlen dagegen lieber mehr f\u00fcr beengte Apartments im Stadtzentrum, wenn sie dadurch Zeit sparen k\u00f6nnen.<\/p>\n<p>Wenn es aber nur ein begrenztes Angebot an Apartments im Stadtzentrum gibt und Ihre wohl-habenden Kollegen ihnen diese wegschnappen, was k\u00f6nnen sie dagegen tun? H\u00e4rter arbeiten. <\/p>\n<p>H\u00e4user wie Keynes&#8216; elegantes Stadthaus in Bloomsbury kosten heute einige Millionen Pfund. Drei Stunden am Tag sind daf\u00fcr bei weitem nicht genug.<\/p>\n<p><em>(Eigene \u00dcbersetzung eines schon \u00e4lteren <a href=\"http:\/\/timharford.com\/2016\/03\/the-lost-leisure-time-of-our-lives\/\" target=\"_blank\" rel=\"noopener\">Blogbeitrages<\/a> des britischen \u00d6konomen <a href=\"https:\/\/de.wikipedia.org\/wiki\/Tim_Harford\" target=\"_blank\" rel=\"noopener\">Tim Harford<\/a>, der aber nichts an Aktualit\u00e4t eingeb\u00fc\u00dft hat)<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>John Maynard Keynes lag schon richtig mit seiner Vorhersage, dass wir weniger arbeiten werden, doch er \u00fcbersch\u00e4tzte, wie lange dieser Trend tats\u00e4chlich anhalten w\u00fcrde. Freizeit-Vergn\u00fcgen im Garten &#8222;Drei Stunden am Tag sind genug&#8220;, schrieb Keynes 1930 in seinem Essay &#8222;Economic<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[43,14,44,18],"class_list":["post-24291205","post","type-post","status-publish","format-standard","hentry","category-oekonomie","tag-keynes","tag-lohn","tag-volkswirtschaftslehre","tag-wirtschaft"],"_links":{"self":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/24291205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/comments?post=24291205"}],"version-history":[{"count":11,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/24291205\/revisions"}],"predecessor-version":[{"id":24411178,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/24291205\/revisions\/24411178"}],"wp:attachment":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/media?parent=24291205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/categories?post=24291205"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/tags?post=24291205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}