{"id":23626284,"date":"2023-09-30T07:00:03","date_gmt":"2023-09-30T05:00:03","guid":{"rendered":"http:\/\/www.joerglipinski.de\/blog\/?p=23626284"},"modified":"2026-06-24T13:00:07","modified_gmt":"2026-06-24T11:00:07","slug":"migration-nach-europa-tatsaechlich-ein-so-grosses-problem","status":"publish","type":"post","link":"http:\/\/www.joerglipinski.de\/blog\/migration-nach-europa-tatsaechlich-ein-so-grosses-problem\/","title":{"rendered":"Migration nach Europa &#8211; tats\u00e4chlich ein so gro\u00dfes Problem?"},"content":{"rendered":"<p>Das aktuelle Theater um die <a href=\"https:\/\/www.tagesschau.de\/faktenfinder\/merz-asylbewerber-zahnarzt-100.html\" rel=\"noopener\" target=\"_blank\">Merz-Aussage zu Zahnbehandlungen von Asylbewerbern<\/a> oder der <a href=\"https:\/\/www.tagesschau.de\/ausland\/europa\/meloni-von-der-leyen-lampedusa-100.html\" rel=\"noopener\" target=\"_blank\">Besuch von Frau von der Leyen und Frau Meloni auf Lampedusa<\/a> vor einigen Wochen zeigt: Das Thema Asyl und Fl\u00fcchtlinge bestimmt offenbar zur Zeit die \u00f6ffentliche Wahrnehmung in Deutschland und Europa.<\/p>\n<p><center><a title=\"Irish Defence Forces, CC BY 2.0 &lt;https:\/\/creativecommons.org\/licenses\/by\/2.0&gt;, via Wikimedia Commons\" href=\"https:\/\/commons.wikimedia.org\/wiki\/File:LE_Eithne_Operation_Triton.jpg\"><img decoding=\"async\" width=\"412\" alt=\"LE Eithne Operation Triton\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/9\/99\/LE_Eithne_Operation_Triton.jpg\"><\/a><br \/>\n<em>Rettung von Fl\u00fcchtlingen im Mittelmeer 2015<\/em><\/center><\/p>\n<p>Aber ist die Migration wirklich ein so dr\u00e4ngendes und alles andere \u00fcberlagerndes Problem in Europa? Oder warum wird mit einem solchen Aufwand eine eigentlich nicht vorhandene Thematik medial so aufgeblasen? <a href=\"https:\/\/commission.europa.eu\/strategy-and-policy\/priorities-2019-2024\/promoting-our-european-way-life\/statistics-migration-europe_de#fl%C3%BCchtlinge-in-europa\" rel=\"noopener\" target=\"_blank\">Laut Europ\u00e4ischer Kommission<\/a> lag der Anteil der Fl\u00fcchtlinge in der EU 2022 bei 1,5 % (!!) der Bev\u00f6lkerung, in Deutschland bei 2,7 %.<\/p>\n<p><!--more Weiterlesen...--><\/p>\n<p>Selbst wenn das in diesem Jahr erheblich mehr sind, w\u00e4re das Ganze bei dezentraler Verteilung in allen Staaten der EU ein eher geringf\u00fcgiges Problem. Mit der derzeitigen Methode der Unterbringung in zentralen Unterk\u00fcnften und Lagern nat\u00fcrlich nicht, gerade auch mit dem begleitenden medialen Get\u00f6se. <\/p>\n<p>Offenbar will man damit von den tats\u00e4chlichen Problemen in der EU ablenken, also von der immer weiter steigenden Ungleichheit, immer noch hohen Arbeits- und Jugenderwerbslosigkeit in manchen Staaten, der hohen Staatsverschuldung in Folge der immer noch nicht gel\u00f6sten Eurokrise und der monet\u00e4ren Fehlkonstruktion des Maastricht-Vertrages. <\/p>\n<p>Nicht zu vergessen die Unf\u00e4higkeit der EU bei nicht vorhandener Einstimmigkeit \u00fcberhaupt Politik machen zu k\u00f6nnen. Auch die institutionelle Sackgasse der Dublin-Abkommen ist ein gutes Beispiel daf\u00fcr.<\/p>\n<p>F\u00fcr Deutschland gilt das \u00fcbrigens \u00e4hnlich, nur sind hier die Probleme teilweise etwas anders gelagert. Zur Ablenkung von den Vers\u00e4umnissen vergangener Jahrzehnte und der Kaschierung nicht vorhan-dener wirklicher Oppositionsarbeit (nicht wahr Herr Merz?) scheint aber ebenso bei uns das Thema Migration gut genug zu sein.<\/p>\n<p>Stattdessen nimmt man dann offenbar auch ein Erstarken der Rechten gerne in Kauf, doch das war ja in der Geschichte eigentlich im Gegenteil noch nie wirklich ein Problem.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das aktuelle Theater um die Merz-Aussage zu Zahnbehandlungen von Asylbewerbern oder der Besuch von Frau von der Leyen und Frau Meloni auf Lampedusa vor einigen Wochen zeigt: Das Thema Asyl und Fl\u00fcchtlinge bestimmt offenbar zur Zeit die \u00f6ffentliche Wahrnehmung in<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[24,18],"class_list":["post-23626284","post","type-post","status-publish","format-standard","hentry","category-oekonomie","tag-globalisierung","tag-wirtschaft"],"_links":{"self":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/23626284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/comments?post=23626284"}],"version-history":[{"count":15,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/23626284\/revisions"}],"predecessor-version":[{"id":23626857,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/23626284\/revisions\/23626857"}],"wp:attachment":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/media?parent=23626284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/categories?post=23626284"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/tags?post=23626284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}