{"id":19107216,"date":"2022-01-17T07:00:29","date_gmt":"2022-01-17T06:00:29","guid":{"rendered":"http:\/\/www.joerglipinski.de\/blog\/?p=19107216"},"modified":"2022-01-14T11:24:56","modified_gmt":"2022-01-14T10:24:56","slug":"to-remember-die-geschichte-wiederholt-sich-doch-nur-die-oekonomen-lernen-offenbar-nichts-daraus","status":"publish","type":"post","link":"http:\/\/www.joerglipinski.de\/blog\/to-remember-die-geschichte-wiederholt-sich-doch-nur-die-oekonomen-lernen-offenbar-nichts-daraus\/","title":{"rendered":"To Remember: Die Geschichte wiederholt sich doch, nur die \u00d6konomen lernen offenbar nichts daraus"},"content":{"rendered":"<blockquote><p><strong>Es lief alles ganz hervorragend f\u00fcr die Reichen, die jeden Kredit bekamen, den sie dazu ben\u00f6tigten, um das Wirtschaftssystem nach den <a href=\"https:\/\/de.wikipedia.org\/wiki\/Koalitionskriege\" target=\"_blank\" rel=\"noopener\">napoleonischen Kriegen<\/a> zwischen rigider Deflation und monet\u00e4rer Orthodoxie einzuklemmen: es war dagegen stets der kleine Mann, der weiterhin litt, und der in allen L\u00e4ndern und zu allen Zeiten des neunzehnten Jahrhunderts leichteren Zugang zu Krediten und eine andere Finanzpolitik forderte.<\/strong><\/p>\n<p><em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Eric_Hobsbawm\" target=\"_blank\" rel=\"noopener\">E. J. Hobsbawm<\/a>,  in seinem Buch <a ref=\"https:\/\/en.wikipedia.org\/wiki\/The_Age_of_Revolution:_Europe_1789%E2%80%931848\" target=\"_blank\" rel=\"noopener\">&#8222;The Age of Revolution 1789 \u2013 1848&#8220;<\/a>, S. 39<\/em><\/p><\/blockquote>\n<p><Center><a title=\"Baumwollspinnerei um 1835 in Gro\u00dfbritannien von Baines (www.handweaving.net Upload User:ClemRutter) [Public domain oder Public domain], via Wikimedia Commons\" href=\"https:\/\/commons.wikimedia.org\/wiki\/File%3ABaines_1835-Mule_spinning.png\"><img decoding=\"async\" width=\"412\" alt=\"Baines 1835-Mule spinning\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/6\/61\/Baines_1835-Mule_spinning.png\"\/><\/a><\/Center><\/p>\n<blockquote><p>\nDie schwersten Konsequenzen [der ersten kapitalistischen Wirtschafts-krisen] waren sozialer Art: die Umstellung auf <a href=\"https:\/\/de.wikipedia.org\/wiki\/Industrielle_Revolution\" target=\"_blank\" rel=\"noopener\">die neue \u00d6konomie<\/a> schuf Elend und Unzufriedenheit, und damit die Materialien f\u00fcr eine soziale Revolution.<\/p><\/blockquote>\n<p><!--more Weiterlesen...--><\/p>\n<blockquote><p>Und in der Tat, die soziale Revolution in Form von spontanen Aufst\u00e4nden der st\u00e4dtischen und industriellen Armen brach aus und gebar die <a href=\"https:\/\/de.wikipedia.org\/wiki\/Europ%C3%A4ische_Revolutionen_1848\/1849\" target=\"_blank\" rel=\"noopener\">Revolten von 1848<\/a> auf dem Kontinent sowie die gewaltige <a href=\"https:\/\/de.wikipedia.org\/wiki\/Chartisten\" target=\"_blank\" rel=\"noopener\">Chartisten<\/a>-Bewegung in Gro\u00dfbritannien.<\/p>\n<p>Doch die Unzufriedenheit beschr\u00e4nkte sich nicht nur auf die arbeitenden Armen. Einfache und eher unflexible Gesch\u00e4ftsleute, kleinb\u00fcrgerliche und andere spezielle Teile der Wirtschaft waren ebenso Opfer der industriellen Revolution und ihrer Auswirkungen.<\/p>\n<p>Eher unbedarfte Arbeiter reagierten auf das neue System, indem sie wie die <a href=\"https:\/\/de.wikipedia.org\/wiki\/Luddismus\" target=\"_blank\" rel=\"noopener\">Ludditen<\/a> die Maschinen <a href=\"https:\/\/de.wikipedia.org\/wiki\/Maschinenst%C3%BCrmer\" target=\"_blank\" rel=\"noopener\">&#8222;erst\u00fcrmten&#8220;<\/a>, die sie f\u00fcr ihre Probleme verant-wortlich machten; aber eine \u00fcberraschend gro\u00dfe Menge an lokalen Gesch\u00e4ftsleuten und Bauern sympathisierte heftig mit diesen st\u00fcrmischen Aktivit\u00e4ten ihrer Arbeiter, da sie sich ebenso als Opfer einer teuflischen Minderheit von selbsts\u00fcchtigen Erneuerern sahen.<\/p>\n<p>Die Ausbeutung der Arbeitskr\u00e4fte, deren Einkommen am Existenzminimum gehalten wurden, erm\u00f6glichte es den Reichen, die Gewinne aus der finanziellen Industrialisierung massiv auszuweiten und rief damit den Widerstand des Proletariats hervor. Aber ein anderer Aspekt dieser Umverteilung des Nationaleinkommens von den Armen zu den Reichen, vom Konsum zur Spekulation, ver\u00e4rgerte auch die kleinen Unternehmer.<\/p>\n<p>Die gro\u00dfen Finanziers, die enge Gemeinschaft von einheimischen und ausl\u00e4ndischen &#8222;Fondsinhabern&#8220;, die all das erhielten, was die Allgemeinheit an Steuern bezahlte &#8211; in etwa um die 8 Prozent des gesamten nationalen Einkommens &#8211; waren bei den kleinen Gesch\u00e4ftsleuten, Bauern und dergleichen wohl noch unbeliebter als unter den Arbeitern, denn diese wussten ihrerseits genug \u00fcber Geld und Kredit, um eine pers\u00f6nliche Wut \u00fcber ihre Nachteile zu empfinden.<\/p><\/blockquote>\n<p>So weit die Stimme von Eric Hobsbawm in seinem bekanntesten Buch \u00fcber das post-napoleonische Europa.<\/p>\n<p>Doch wie aktuell ist diese Ansicht heute?<\/p>\n<p>Wir befinden uns derzeit in einer \u00e4hnlichen Situation. Unsere Elite, sowohl in den USA als auch in Europa, verwaltet die Wirtschaft f\u00fcr ihre eigenen Zwecke. Die Abschottung zum allt\u00e4glichen Volk ist erstaunlich. Die Hybris und schlichte Niedertr\u00e4chtigkeit des Ganzen ist ebenso erstaunlich.<\/p>\n<p>Schauen Sie sich Griechenland an: der Versuch, eine teutonische &#8222;Fiskaldisziplin&#8220; \u00fcber eine strenge Sparpolitik durchzusetzen hat schlichtweg die Schulden, deren Reduzierung eigentlich das Ziel dieser Politik darstellten sollte, zu einem noch gr\u00f6\u00dferen Problem gemacht. Es ist ein Beispiel f\u00fcr episches Politikversagen. Den Griechen, trotz all ihrer fr\u00fcheren Laxheit und fiskalen Unf\u00e4higkeit, ist f\u00fcr ihren Ruf nach einem Ende der Dummheit zu applaudieren.<\/p>\n<p>Au\u00dferdem ist es nicht nur dumm, sondern zudem auch unbarmherzig grausam.<\/p>\n<p>F\u00fcr die politischen Entscheidungstr\u00e4ger bedeutet das Ignorieren der menschlichen Folgen ihrer Initiativen eine monstr\u00f6se ethische Doppeldeutigkeit. Gerade \u00d6konomen neigen dazu, ihre K\u00f6pfe in den Sand zu stecken und vorzugeben, dass das, was sie vermuten nur eine Theorie sei und die realen Folgen nicht deren Konsequenzen sondern nur zuf\u00e4llige Unf\u00e4lle w\u00e4ren. <\/p>\n<p>Das bedeutet, dass die menschlichen Verw\u00fcstungen nicht das Ergebnis einer Theorie darstellen, die ein gl\u00fcckliches Ende, mehr Effizienz und das Nirvana der Optimierung versprochen hatte. Offenbar sind solche verheerenden Folgen f\u00fcr diejenigen, die eine Politik auf der Grundlage solcher Theorien vorschlagen, einfach nur notwendige \u00dcbel auf dem Weg zu diesem Happy End. Je heftiger die menschliche Katastrophe ausf\u00e4llt, desto gr\u00f6\u00dfer wird die Kluft zwischen Realit\u00e4t und Utopie. Und umso st\u00e4rker wird auch das Argument f\u00fcr ihre L\u00f6sungsvorschl\u00e4ge, sagen dann die Anh\u00e4nger einer solchen Glaubensrichtung.<\/p>\n<p>Also das Dorf niederbrennen, um es zu retten?<\/p>\n<p>Den \u00d6konomen, die utopische theoretische Konstrukte vorschlagen, muss die Verantwortung f\u00fcr die menschlichen Kosten ihres extremen Glaubens vorgehalten werden. Sie sind entweder unmoralisch, weil sie sich nicht um die Kosten f\u00fcr das, was sie vorschlagen k\u00fcmmern; oder sie sind zusammen mit der Elite mitschuldig und wollen an der Unterdr\u00fcckung teilnehmen. Oder beides.<\/p>\n<p>Es ist entmutigend, dass die \u00d6konomie so engstirnig geworden ist, ihre eigene Geschichte zu ignorieren. Nicht nur die Wirtschaftsgeschichte, sondern die Geschichte der \u00f6konomischen Lehre selbst.<\/p>\n<p>Wie kann das sein?<\/p>\n<p>Die Volkswirtschaftslehre sollte, trotz allem, einfach nur Volkswirtschaften erkl\u00e4ren und beschreiben. Und Volkswirtschaften sind in einem st\u00e4ndigen Fluss. Und so m\u00fcsste auch die \u00f6konomische Lehre im Fluss und in der Lage sein, sich im Gleichschritt mit der Wirtschaft zu ver\u00e4ndern. <\/p>\n<p>Eine Theorie, die in einem primitiven industriellen Umfeld funktioniert, ist in unserem erweiterten und komplexeren, miteinander verbundenen und doch sehr b\u00fcrokratischen Rahmen m\u00f6glicherweise nicht mehr ganz so gut. Und gro\u00dfe intellektuelle Energie f\u00fcr zeitlose Wahrheiten aufzuwenden, erscheint da eher als reine Verschwendung. Nicht, dass es keine Konstanten g\u00e4be, doch diese Konstanten sind in der Regel unter einem Haufen von kurzlebigen und anderen kurzfristig wichtigen Auswirkungen begraben.<\/p>\n<p>Und viele dieser anderen Effekte sind in ihren Urspr\u00fcngen politischer, kultureller, institutioneller, geografischer, erkenntnistheoretischer oder einfach nur menschlicher Natur.<\/p>\n<p>Wie auch immer, eine allgemeing\u00fcltige Konstante wird sein, dass sich die Reichen weiterhin in Bezug auf die Deflation irren. Sie werden dagegen immerfort die Tugenden der Kreditw\u00fcrdigkeit preisen. Sie werden sich \u00fcber den geringsten Anflug von Inflation beschweren. Und sie werden alles tun, um die Politik weiter f\u00fcr ihren eigenen Vorteil arbeiten zu lassen.<\/p>\n<p>Eines der h\u00e4ufigsten Themen derjenigen, die die politische Agitation in der Zeit unmittelbar nach den Napoleonischen Kriegen betrieben, egal ob in Frankreich, Gro\u00dfbritannien oder den Vereinigten Staaten, war ihr Wunsch, heterodoxer \u00d6konomie zu folgen. Orthodoxie war und ist stets eine intellektuelle Verteidigung der Elite.<\/p>\n<p>So wie jetzt. Richtig?<\/p>\n<p><em>(eigene \u00dcbersetzung und Erweiterung eines immer noch sehr lesenswerten <a href=\"https:\/\/rwer.wordpress.com\/2015\/02\/10\/rats-history-does-repeat-itself\/\" target=\"_blank\" rel=\"noopener\">Blogbeitrages<\/a> des amerikanischen \u00d6konomen <a href=\"https:\/\/www.linkedin.com\/pub\/peter-radford\/8\/642\/972\" target=\"_blank\" rel=\"noopener\">Peter Radford<\/a>)<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Es lief alles ganz hervorragend f\u00fcr die Reichen, die jeden Kredit bekamen, den sie dazu ben\u00f6tigten, um das Wirtschaftssystem nach den napoleonischen Kriegen zwischen rigider Deflation und monet\u00e4rer Orthodoxie einzuklemmen: es war dagegen stets der kleine Mann, der weiterhin litt,<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[33,34,32,29,44,18],"class_list":["post-19107216","post","type-post","status-publish","format-standard","hentry","category-oekonomie","tag-deflation","tag-inflation","tag-schulden","tag-sparen","tag-volkswirtschaftslehre","tag-wirtschaft"],"_links":{"self":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/19107216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/comments?post=19107216"}],"version-history":[{"count":7,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/19107216\/revisions"}],"predecessor-version":[{"id":24411344,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/19107216\/revisions\/24411344"}],"wp:attachment":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/media?parent=19107216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/categories?post=19107216"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/tags?post=19107216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}