{"id":13787425,"date":"2020-05-10T07:00:35","date_gmt":"2020-05-10T05:00:35","guid":{"rendered":"http:\/\/www.joerglipinski.de\/blog\/?p=13787425"},"modified":"2026-04-15T14:44:22","modified_gmt":"2026-04-15T12:44:22","slug":"usa-wie-die-blauen-staaten-den-roten-staaten-helfen","status":"publish","type":"post","link":"http:\/\/www.joerglipinski.de\/blog\/usa-wie-die-blauen-staaten-den-roten-staaten-helfen\/","title":{"rendered":"USA &#8211; Wie die Blauen Staaten den Roten Staaten helfen"},"content":{"rendered":"<p>Donald Trump und die Republikaner im Kongress lieben es Staatshilfen der Regierung zu d\u00e4monisieren, von denen allerdings ihre eigenen Unterst\u00fctzer abh\u00e4ngig sind und die zunehmend von Steuerzahlern in den &#8222;Blauen&#8220; Staaten finanziert werden.<\/p>\n<p><center><a title=\"Angr, CC BY-SA 3.0 &lt;http:\/\/creativecommons.org\/licenses\/by-sa\/3.0\/&gt;, via Wikimedia Commons\" href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Red_states_and_blue_states_of_the_US_based_on_data_from_the_2008,_2012,_2016_and_2020_presidential_elections.svg\"><img decoding=\"async\" width=\"412\" alt=\"Red states and blue states of the US based on data from the 2008, 2012, 2016 and 2020 presidential elections\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/b\/b4\/Red_states_and_blue_states_of_the_US_based_on_data_from_the_2008%2C_2012%2C_2016_and_2020_presidential_elections.svg\"><\/a><br \/>\n<em>Karte der sogenannten &#8222;<a href=\"https:\/\/de.wikipedia.org\/wiki\/Rote_Staaten_und_blaue_Staaten\" rel=\"noopener noreferrer\" target=\"_blank\">Roten und Blauen Staaten<\/a>&#8220; der USA<\/em><\/center><\/p>\n<p>Das Bundesprogramm <a href=\"https:\/\/en.wikipedia.org\/wiki\/Temporary_Assistance_for_Needy_Families\" rel=\"noopener noreferrer\" target=\"_blank\">Temporary Assistance for Needy Families<\/a> &#8211; was wir fr\u00fcher schlicht als \u201eWohlfahrt\u201c bezeichneten &#8211; bietet weniger als einem Prozent der Amerikaner Bargeldhilfe. Die Trump-Regierung schl\u00e4gt jedoch vor, viele Sozialprogramme unter einer neuen Agentur zusammenzufassen, deren Titel das Wort \u201eWohlfahrt\u201c enth\u00e4lt.<\/p>\n<p><!--more Weiterlesen...--><\/p>\n<p>In einem k\u00fcrzlich ver\u00f6ffentlichten Bericht des Wei\u00dfen Hauses \u00fcber die Auferlegung von Arbeitsanforderungen wurden beispielsweise Medicaid, Nahrungsmittelhilfe und Wohnungsbeihilfe in ein umbenanntes Programm mit dem Namen \u201eNoncash Welfare\u201c aufgenommen.<\/p>\n<p>Ein gro\u00dfer Teil Amerikas ist auf Wohlfahrt angewiesen. Wenn man Invalidit\u00e4tsleistungen, Arbeitslosenversicherung und medizinische Leistungen hinzuf\u00fcgt macht das sogenannte \u201eWohlergehen\u201c 17 Prozent des durchschnittlichen amerikanischen Einkommens aus.<\/p>\n<p>Diese Wohlfahrt ist allerdings in \u201eroten\u201c Staaten, die Republikaner w\u00e4hlen und Trump unterst\u00fctzen, besonders unbeliebt geworden. Dieselben Staaten sind jedoch h\u00e4ufig die gr\u00f6\u00dften Nutznie\u00dfer staatlicher Unterst\u00fctzung.<\/p>\n<p>Ber\u00fccksichtigt man Preisst\u00fctzungen f\u00fcr die Landwirtschaft, Subventionen f\u00fcr Land- und Forstwirtschaft sowie f\u00fcr R\u00fcstungsunternehmen, so kann man feststellen, dass ein gro\u00dfer Teil der Volkswirtschaften der roten Staaten von den Bundesdollars abh\u00e4ngen.<\/p>\n<p>Hier ist dann auch die Ironie. Einwohner von \u201eblauen\u201c Staaten senden mehr Steuergelder nach Washington als sie in Form von Bundeshilfe zur\u00fcckbekommen, w\u00e4hrend Einwohner von \u201eroten\u201c Staaten weniger Geld nach Washington senden, als sie in Bundeshilfe zur\u00fcckerhalten.<\/p>\n<p>Im Jahr 2015 erhielt New Jersey beispielsweise nur 74 Cent an Bundesausgaben f\u00fcr jeden Steuerdollar, den es nach Washington schickte. New York bekam 81 Cent zur\u00fcck, Connecticut 82 Cent und Massachusetts 83 Cent.<\/p>\n<p>Wenn Sie sich jedoch den roten Zust\u00e4nden zuwenden ist das Gegenteil der Fall. Mississippi erhielt 2,13 Dollar f\u00fcr jeden Steuerdollar, den es nach Washington schickte. West Virginia: 2,07 USD. Kentucky: 1,90 USD. Und South Carolina: 1,71 Dollar.<\/p>\n<p>Ausgehend von der expansiven Sichtweise der Trump-Regierung auf die Bedeutung von Wohlfahrt zu ihrer logischen Schlussfolgerung, alle diejenigen einzubeziehen, die von Bundesausgaben profitieren, senden blaue Staaten Wohlfahrt an rote Staaten &#8211; dieselben roten Staaten, die sagen, dass sie Wohlfahrt nicht m\u00f6gen.<\/p>\n<p>Nach dem neuen Steuergesetz von Trump werden die blauen Staaten den roten Staaten noch mehr Sozialhilfe geben. Dies liegt daran, dass das Gesetz neue Grenzen f\u00fcr die H\u00f6he der staatlichen und lokalen Steuern festlegt, die Menschen von ihrem steuerpflichtigen Bundeseinkommen abziehen k\u00f6nnen. Und da Menschen in blauen Bundesstaaten viel mehr staatliche und lokale Steuern zahlen als Menschen in roten Bundesstaaten, zahlen Blue-Staters so auch viel mehr Bundessteuern.<\/p>\n<p>Dies bedeutet einen noch gr\u00f6\u00dferen Transfer von den Bewohnern des blauen Staates zu all jenen republikanischen W\u00e4hlern des roten Staates, deren Partei staatliche Zuwendungen verachtet.<\/p>\n<p>Nun sollte man hinzuf\u00fcgen, dass es einigen in den blauen Staaten nichts ausmacht roten Staaten eine gr\u00f6\u00dfere helfende Hand zu geben. Die \u00fcberwiegende Mehrheit der Amerikaner ist auch gegen K\u00fcrzungen bei Programmen die Armen, Alten und Kranken helfen. Weil die meisten Amerikaner glauben, dass wir alle zusammengeh\u00f6ren und diejenigen von uns die sich das leisten k\u00f6nnen den Bed\u00fcrftigen auch helfen sollten.<\/p>\n<p>Wir betrachten es nicht als Sozialhilfe. Wir nennen es Sozialversicherung. In der Tat wird die Sozialversicherung von fast allen von uns ben\u00f6tigt und genutzt, wenn Sie die soziale Absicherung, die Krankenversicherung und die Arbeitslosenversicherung einbeziehen. Und selbst Programme, auf die sich die Armen haupts\u00e4chlich verlassen helfen einem gro\u00dfen Teil von uns, weil ungef\u00e4hr ein Drittel aller Amerikaner irgendwann in ihrem Leben arm sind.<\/p>\n<p>Denken Sie also daran, Angriffe auf das sogenannte Wohlergehen sind nur ein weiteres Mittel, um die Dinge anzugreifen, die die meisten von uns brauchen, und das Land weiter zu spalten. In Wirklichkeit sind W\u00e4hler in roten Staaten ebenso abh\u00e4ngig von der Bundesregierung wie W\u00e4hler in blauen Staaten und, um ehrlich zu sein, noch etwas mehr.<\/p>\n<p><em>(Eigene \u00dcbersetzung eines <a href=\"https:\/\/www.salon.com\/2018\/11\/16\/how-blue-states-help-red-states_partner\/\" rel=\"noopener noreferrer\" target=\"_blank\">Blogbeitrages<\/a> des amerikanischen \u00d6konomen <a href=\"https:\/\/en.wikipedia.org\/wiki\/Robert_Reich\" rel=\"noopener noreferrer\" target=\"_blank\">Robert Reich<\/a>)<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Donald Trump und die Republikaner im Kongress lieben es Staatshilfen der Regierung zu d\u00e4monisieren, von denen allerdings ihre eigenen Unterst\u00fctzer abh\u00e4ngig sind und die zunehmend von Steuerzahlern in den &#8222;Blauen&#8220; Staaten finanziert werden. Karte der sogenannten &#8222;Roten und Blauen Staaten&#8220;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[18],"class_list":["post-13787425","post","type-post","status-publish","format-standard","hentry","category-oekonomie","tag-wirtschaft"],"_links":{"self":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/13787425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/comments?post=13787425"}],"version-history":[{"count":10,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/13787425\/revisions"}],"predecessor-version":[{"id":24327511,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/posts\/13787425\/revisions\/24327511"}],"wp:attachment":[{"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/media?parent=13787425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/categories?post=13787425"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.joerglipinski.de\/blog\/wp-json\/wp\/v2\/tags?post=13787425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}